{"id":29187,"date":"2026-06-06T07:50:10","date_gmt":"2026-06-06T07:50:10","guid":{"rendered":"https:\/\/abstruse.nl\/?p=29187"},"modified":"2026-06-06T07:50:10","modified_gmt":"2026-06-06T07:50:10","slug":"voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104","status":"publish","type":"post","link":"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/","title":{"rendered":"Voel Weer Rust in je Woning of Werkplek in Lier"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhoud van deze pagina:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Tabel met inhoud schakelen\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Schakel<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Titel\" >Titel:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Inleiding\" >Inleiding:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Wat_is_een_huisreiniging\" >Wat is een huisreiniging?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Wanneer_is_energetische_huisreiniging_nodig\" >Wanneer is energetische huisreiniging nodig?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Gevoeligheid_bij_kinderen\" >Gevoeligheid bij kinderen:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Onrust_op_school\" >\ud83c\udf00Onrust op school:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Waarom_het_energetisch_geheugen_reinigen\" >\ud83c\udf00Waarom het energetisch geheugen reinigen:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Wat_merk_je_na_energetische_huisreiniging\" >Wat merk je na energetische huisreiniging:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Wat_kost_een_energetische_huisreiniging\" >Wat kost een energetische huisreiniging?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/#%F0%9F%8C%80Conclusie_en_combinatie_met_healing\" >\ud83c\udf00Conclusie en combinatie met healing:<\/a><\/li><\/ul><\/nav><\/div>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Titel\"><\/span>\ud83c\udf00<strong>Titel:<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Energetische Huiszuivering<br \/>\nin Lier:<br \/>\nBreng Harmonie Terug<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Inleiding\"><\/span>Inleiding:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Een energetische huisreiniging<br \/>\nis een heilige manier om<br \/>\nongewenste invloeden<br \/>\nuit je praktijkruimte te verwijderen.<\/p>\n<p>Wanneer je merkt dat de sfeer gespannen aanvoelt,<br \/>\nkan een huisreiniging<br \/>\neen energetische reset bieden.<\/p>\n<p>De energetische zuivering kan plaatsvinden in de Lier.<\/p>\n<p>In overleg is een energetische reiniging overal ter wereld uitvoerbaar.<br \/>\nIk ben regelmatig actief in de regio Valencia (Spanje),<br \/>\nwat aantrekkelijk kan zijn qua reiskosten.<\/p>\n<p>Ontdek de diverse opties voor uw ruimte in Lier.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wat_is_een_huisreiniging\"><\/span>Wat is een huisreiniging?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Hoe werkt een energetische zuivering van je woning?<\/p>\n<p>Een energetische huisreiniging<br \/>\nis het opschonen van een woning<br \/>\nop trillingsniveau.<\/p>\n<p>Hierbij worden negatieve energie\u00ebn<br \/>\nlosgelaten<br \/>\nmet behulp van Reiki-energie.<\/p>\n<p>Het doel is om de lichte trilling<br \/>\nin het pand te herstellen.<br \/>\nNa de reiniging voelt de ruimte weer licht, veilig en aangenaam.<\/p>\n<p>Ook deze energetische huisreiniging is beschikbaar in de Lier.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wanneer_is_energetische_huisreiniging_nodig\"><\/span>Wanneer is energetische huisreiniging nodig?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>In welke situaties helpt een huisreiniging?<\/p>\n<p>Er zijn veel gevoelens die erop wijzen dat een pand<br \/>\nenergetisch uit balans is.<br \/>\nHerken je dit? Dan kan een energetische opschoning in Lier verlichting brengen.<\/p>\n<p>**Signalen in huis**<br \/>\n- Gevoel van zwaarte of drukkende sfeer<br \/>\n- Onrustige nachten<br \/>\n- Plotselinge lichamelijke klachten zonder reden<br \/>\n- Moeite met ontspannen in huis<br \/>\n- Voortdurende ruzies of spanningen<br \/>\n- Een afstandelijk of koud gevoel in huis<br \/>\n- Het gevoel dat er energie aanwezig is die niet van jou is<\/p>\n<p>De energetische huisreiniging in de Lier brengt rust en helderheid terug.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Gevoeligheid_bij_kinderen\"><\/span>Gevoeligheid bij kinderen:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Jonge kinderen voelen energie sterker aan dan volwassenen.<br \/>\nTot ongeveer tien jaar kunnen zij trillingen ervaren die voor anderen onzichtbaar zijn.<\/p>\n<p>**Mogelijke signalen bij kinderen**<br \/>\n- Niet willen slapen in hun eigen kamer<br \/>\n- Plotselinge huilbuien in de nacht<br \/>\n- Dalende schoolprestaties<br \/>\n- Moeite om aansluiting te vinden<br \/>\n- Emotioneel instabiel gedrag<\/p>\n<p>Een healing van de woonenergie in Lier<br \/>\nkan de nachtrust verbeteren.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Onrust_op_school\"><\/span>\ud83c\udf00Onrust op school:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Een school kan onbewust veel emotionele lading dragen.<br \/>\nEen energetische schoolreiniging in Lier helpt bij:<\/p>\n<p>- Veel chaos in de klas<br \/>\n- Leraren met weinig energie of motivatie<br \/>\n- Kinderen die vaak vallen of lichamelijke klachten hebben<br \/>\n- Een gespannen of prettige sfeer<\/p>\n<p>Na de reiniging heerst er meer harmonie in de klas.<br \/>\nScholen in Lier ervaren vaak meer plezier en balans.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Waarom_het_energetisch_geheugen_reinigen\"><\/span>\ud83c\udf00Waarom het energetisch geheugen reinigen:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Waarom blijft oude energie soms hangen?<\/p>\n<p>Naast het zuiveren van de actuele energie is het ook essentieel om het<br \/>\ntrillingsveld<br \/>\nvan een pand te opschonen.<br \/>\nRuimtes nemen oude ervaringen op,<br \/>\nen die kan zich vastzetten in muren of meubels.<\/p>\n<p>Voorbeelden waarbij dit waardevol is:<br \/>\n- Er is veel verdriet of ruzie geweest in het huis<br \/>\n- Het pand voelt \u201cuitgeput\u201d of zwaar<br \/>\n- Er zijn entiteiten blijven hangen<br \/>\n- Er vond een tragische gebeurtenis of zelfdoding plaats<\/p>\n<p>Een diepe energetische zuivering<br \/>\nmaakt de ruimte weer uitnodigend en veilig.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wat_merk_je_na_energetische_huisreiniging\"><\/span>Wat merk je na energetische huisreiniging:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wat merk je na een energetische huisreiniging?<\/p>\n<p>Na de reiniging heerst er rust en helderheid.<br \/>\nVeel mensen in De Lier ervaren direct meer balans en ontspanning.<\/p>\n<p>**In huis**<br \/>\n- Een warme en veilige sfeer<br \/>\n- Diepere en betere slaap<br \/>\n- Meer vitaliteit<br \/>\n- Planten bloeien weer op<br \/>\n- Een gevoel van veiligheid en thuis zijn<\/p>\n<p>**Op het werk**<br \/>\n- Betere focus en samenwerking<br \/>\n- Meer inspiratie en motivatie<br \/>\n- Minder stress en spanning<\/p>\n<p>**Op school**<br \/>\n- Kinderen zijn rustiger en geconcentreerder<br \/>\n- Meer plezier in lesgeven<br \/>\n- Een positieve, veilige sfeer<\/p>\n<p>Een heling van huizen en werkplekken in Lier<br \/>\nzorgt voor een voelbare energetische reset.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wat_kost_een_energetische_huisreiniging\"><\/span>Wat kost een energetische huisreiniging?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wat zijn de tarieven voor energetische opschoning?<\/p>\n<p>De prijzen liggen rond **\u20ac 323,-**<br \/>\nvoor een rijtjeswoning.<br \/>\nVoor andere woningtypes of panden<br \/>\nwordt een persoonlijke offerte gemaakt.<\/p>\n<p>Afhankelijk van de locatie worden reiskosten gerekend,<br \/>\nzeker bij sessies buiten de Lier.<\/p>\n<p>Een reinigen van huizen in andere landen<br \/>\nis regelmatig uitvoerbaar.<br \/>\nIk ben vaak actief rond Valencia,<br \/>\nwat reiskosten kan verlagen.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Conclusie_en_combinatie_met_healing\"><\/span>\ud83c\udf00Conclusie en combinatie met healing:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Gun jezelf een schone energetische start.<\/p>\n<p>Of het nu om je woning, werkplek of school gaat -...<br \/>\neen energetische opschoning<br \/>\nkan wonderen doen op de<br \/>\nsfeer, gezondheid en harmonie.<\/p>\n<p>Stel het niet uit als je merkt dat er iets uit balans is<br \/>\nin je omgeving.<br \/>\nJe verdient een huis dat als thuis voelt.<\/p>\n<p>In sommige gevallen is het waardevol om de reiniging te koppelen aan persoonlijke genezing.<br \/>\nDat werkt op persoonlijke energievelden,<br \/>\nwaardoor het resultaat krachtiger en blijvend is.<\/p>\n<p>Deze vorm van healing wordt regelmatig toegepast in Lier<br \/>\nen biedt diepe transformatie.<\/p>\n<p>&nbsp;<\/p>\n<p>Neem contact op via Whatsapp +31 6 38398347 of met onderstaand formulier.<\/p>\n<div class=\"forminator-ui forminator-custom-form forminator-custom-form-150 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-150\" data-uid=\"6a5706b1ad33a\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-150\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-150 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"150\"\n\t\t\t\t data-color-option=\"default\" data-design=\"default\" data-grid=\"open\" style=\"display: none;\"\n\t\t\t\tdata-uid=\"6a5706b1ad33a\" action=\"\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-name-1_6a5706b1ad33a\" id=\"forminator-field-name-1_6a5706b1ad33a-label\" class=\"forminator-label\">Voornaam <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1\" value=\"\" placeholder=\"\" id=\"forminator-field-name-1_6a5706b1ad33a\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"name-2\" class=\"forminator-field-name forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-name-2_6a5706b1ad33a\" id=\"forminator-field-name-2_6a5706b1ad33a-label\" class=\"forminator-label\">Achternaam <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-2\" value=\"\" placeholder=\"\" id=\"forminator-field-name-2_6a5706b1ad33a\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"phone-1\" class=\"forminator-field-phone forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-phone-1_6a5706b1ad33a\" id=\"forminator-field-phone-1_6a5706b1ad33a-label\" class=\"forminator-label\">Telefoonnummer<\/label><input type=\"text\" name=\"phone-1\" value=\"\" placeholder=\"\" id=\"forminator-field-phone-1_6a5706b1ad33a\" class=\"forminator-input forminator-field--phone\" data-required=\"\" aria-required=\"false\" autocomplete=\"off\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-4\"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a5706b1ad33a\" id=\"forminator-field-email-1_6a5706b1ad33a-label\" class=\"forminator-label\">E-mailadres <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"\" id=\"forminator-field-email-1_6a5706b1ad33a\" class=\"forminator-input forminator-email--field\" data-required=\"true\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><div id=\"captcha-1\" class=\"forminator-field-captcha  forminator-col-4\"><div class=\"forminator-captcha-left forminator-g-recaptcha recaptcha-invisible\" data-theme=\"light\" data-badge=\"bottomright\" data-sitekey=\"6LeZ3CgqAAAAAOurPts9xhQkmYl-TBrc_QHZGS-Z\" data-size=\"invisible\"><\/div> <\/div><div id=\"textarea-1\" class=\"forminator-field-textarea forminator-col forminator-col-4\"><div class=\"forminator-field\"><label for=\"forminator-field-textarea-1_6a5706b1ad33a\" id=\"forminator-field-textarea-1_6a5706b1ad33a-label\" class=\"forminator-label\">Bericht<\/label><textarea name=\"textarea-1\" placeholder=\"Voer je bericht in...\" id=\"forminator-field-textarea-1_6a5706b1ad33a\" class=\"forminator-textarea\" style=\"--forminator-textarea-min-height:140px;\" maxlength=\"180\" ><\/textarea><span id=\"forminator-field-textarea-1_6a5706b1ad33a-description\" class=\"forminator-description\"><span data-limit=\"180\" data-type=\"characters\" data-editor=\"\">0 \/ 180<\/span><\/span><\/div><\/div><\/div><div class=\"forminator-row forminator-hidden\"><div id=\"hidden-1\" class=\"forminator-field-hidden  forminator-col-12\"><input type=\"hidden\" id=\"hidden-1_6a5706b1ad33a\" name=\"hidden-1\" value=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/\" \/><\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">Bericht verzenden<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"e3a36e4f47\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/nl\/wp-json\/wp\/v2\/posts\/29187\" \/><input type=\"hidden\" name=\"form_id\" value=\"150\"><input type=\"hidden\" name=\"page_id\" value=\"29187\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><label for=\"input_7\" class=\"forminator-hidden\" aria-hidden=\"true\">Voer dit veld niet in. <input id=\"input_7\" type=\"text\" name=\"input_7\" value=\"\" autocomplete=\"off\"><\/label><input type=\"hidden\" name=\"trp-form-language\" value=\"nl\"\/><\/form>","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf00Titel: Energetische Huiszuivering in Lier: Breng Harmonie Terug \ud83c\udf00Inleiding: Een energetische huisreiniging is een heilige manier om ongewenste invloeden uit je praktijkruimte te verwijderen. Wanneer je merkt dat de sfeer gespannen aanvoelt, kan een huisreiniging een energetische reset bieden. De energetische zuivering kan plaatsvinden in de Lier. In overleg is een energetische reiniging overal ter &hellip; <a href=\"https:\/\/abstruse.nl\/nl\/voel-weer-rust-in-je-woning-of-werkplek-in-lier-pageid-104\/\" class=\"more-link\">Verder lezen<span class=\"screen-reader-text\"> &#8220;Voel Weer Rust in je Woning of Werkplek in Lier PageID= 104&#8221;<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_page_generator_pro_exclude":false,"_page_generator_pro_group":1766,"_page_generator_pro_index":4404,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29187","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/posts\/29187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/comments?post=29187"}],"version-history":[{"count":1,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/posts\/29187\/revisions"}],"predecessor-version":[{"id":35601,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/posts\/29187\/revisions\/35601"}],"wp:attachment":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/media?parent=29187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/categories?post=29187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/tags?post=29187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}