{"id":25725,"date":"2021-04-16T22:56:13","date_gmt":"2021-04-16T22:56:13","guid":{"rendered":"https:\/\/abstruse.nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/"},"modified":"2021-04-16T22:56:13","modified_gmt":"2021-04-16T22:56:13","slug":"energetische-opschoning-van-ruimtes-in-boechout-pageid-142","status":"publish","type":"post","link":"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/","title":{"rendered":"Energetische Ruimtezuivering in Boechout PaginaID= 142"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhoud van deze pagina:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Tabel met inhoud schakelen\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Schakel<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Titel\" >Titel:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Inleiding\" >Inleiding:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Wat_is_een_huisreiniging\" >Wat is een huisreiniging?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Wanneer_is_energetische_huisreiniging_nodig\" >Wanneer is energetische huisreiniging nodig?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Gevoeligheid_bij_kinderen\" >Gevoeligheid bij kinderen:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Onrust_op_school\" >\ud83c\udf00Onrust op school:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Waarom_het_energetisch_geheugen_reinigen\" >\ud83c\udf00Waarom het energetisch geheugen reinigen:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Wat_merk_je_na_energetische_huisreiniging\" >Wat merk je na energetische huisreiniging:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Wat_kost_een_energetische_huisreiniging\" >Wat kost een energetische huisreiniging?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/#%F0%9F%8C%80Conclusie_en_combinatie_met_healing\" >\ud83c\udf00Conclusie en combinatie met healing:<\/a><\/li><\/ul><\/nav><\/div>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Titel\"><\/span>\ud83c\udf00<strong>Titel:<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Helende Huisreiniging<br \/>\nin Boechout:<br \/>\nBreng Harmonie Terug<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Inleiding\"><\/span>Inleiding:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Een energetische huisreiniging<br \/>\nis een effectieve manier om<br \/>\nenergetische blokkades<br \/>\nuit je woning te verwijderen.<\/p>\n<p>Wanneer je merkt dat er onverklaarbare vermoeidheid of irritatie ontstaat,<br \/>\nkan een huisreiniging<br \/>\neen verlichting bieden.<\/p>\n<p>De energetische zuivering kan plaatsvinden in Boechout.<\/p>\n<p>In overleg is een energetische reiniging wereldwijd mogelijk.<br \/>\nIk ben regelmatig in de buurt van Valencia,<br \/>\nwat gunstig kan zijn qua reiskosten.<\/p>\n<p>Ontdek de diverse opties voor jouw ruimte in Boechout.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wat_is_een_huisreiniging\"><\/span>Wat is een huisreiniging?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wat houdt een energetische huisreiniging precies in?<\/p>\n<p>Een spirituele zuivering<br \/>\nis het opschonen van een ruimte<br \/>\nop energetisch niveau.<\/p>\n<p>Hierbij worden oude trillingen<br \/>\ngeneutraliseerd<br \/>\nmet behulp van Reiki-energie.<\/p>\n<p>Het doel is om de harmonie<br \/>\nin het pand terug te brengen.<br \/>\nDe plek voelt opnieuw als jouw thuis.<\/p>\n<p>Ook deze energetische huisreiniging is beschikbaar in Boechout.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wanneer_is_energetische_huisreiniging_nodig\"><\/span>Wanneer is energetische huisreiniging nodig?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wanneer voelt een energetische zuivering juist?<\/p>\n<p>Er zijn veel gevoelens die erop wijzen dat een huis<br \/>\nonrustig is.<br \/>\nHerken je dit? Dan kan een zuivering in Boechout verlichting brengen.<\/p>\n<p>**Signalen in huis**<br \/>\n- Gevoel van zwaarte of drukkende sfeer<br \/>\n- Slechte nachtrust van nachtmerries<br \/>\n- Plotselinge lichamelijke klachten zonder reden<br \/>\n- Moeite met ontspannen in huis<br \/>\n- Voortdurende ruzies of spanningen<br \/>\n- Je niet thuis voelen in je eigen woning<br \/>\n- Het gevoel dat er energie aanwezig is die niet van jou is<\/p>\n<p>De energetische huisreiniging in Boechout helpt deze energie te transformeren.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Gevoeligheid_bij_kinderen\"><\/span>Gevoeligheid bij kinderen:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Jonge kinderen voelen energie sterker aan dan volwassenen.<br \/>\nTot ongeveer tien jaar kunnen zij de aanwezigheid van zielen voelen.<\/p>\n<p>**Mogelijke signalen bij kinderen**<br \/>\n- Bang zijn om naar bed te gaan<br \/>\n- Plotselinge huilbuien in de nacht<br \/>\n- Minder concentratie op school<br \/>\n- Moeite om aansluiting te vinden<br \/>\n- Snel overprikkeld van boegeroep<\/p>\n<p>Een energetische huisreiniging in Boechout<br \/>\nkan veiligheid en ontspanning herstellen.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Onrust_op_school\"><\/span>\ud83c\udf00Onrust op school:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ook scholen hebben een eigen energie.<br \/>\nEen energetische schoolreiniging in Boechout helpt bij:<\/p>\n<p>- Veel chaos in de klas<br \/>\n- Leraren met weinig energie of motivatie<br \/>\n- Plotselinge ongelukjes of onrust in de groep<br \/>\n- Gebrek aan roest en concentratie<\/p>\n<p>Na de reiniging heerst er meer harmonie in de klas.<br \/>\nScholen in Boechout kennen vaak tevreden leerlingen en leerkrachten.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Waarom_het_energetisch_geheugen_reinigen\"><\/span>\ud83c\udf00Waarom het energetisch geheugen reinigen:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Waarom is het belangrijk om het energetisch geheugen van een pand te reinigen?<\/p>\n<p>Naast het zuiveren van de actuele energie is het ook essentieel om het<br \/>\nenergetisch geheugen<br \/>\nvan een pand te reinigen.<br \/>\nRuimtes nemen emoties van vorige bewoners op,<br \/>\nen die kan zich vastzetten in muren of meubels.<\/p>\n<p>Voorbeelden waarbij dit waardevol is:<br \/>\n- Vorige bewoners zijn gescheiden of overleden<br \/>\n- Het pand voelt \u201cuitgeput\u201d of zwaar<br \/>\n- Er zijn entiteiten blijven hangen<br \/>\n- De geschiedenis drukt nog door op het heden<\/p>\n<p>Een spirituele herprogrammering van het pand<br \/>\nherstelt de neutraliteit.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wat_merk_je_na_energetische_huisreiniging\"><\/span>Wat merk je na energetische huisreiniging:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Welke effecten kun je verwachten?<\/p>\n<p>Na de reiniging heerst er rust en helderheid.<br \/>\nVeel mensen in Boechout ervaren direct diepe rust en verbondenheid.<\/p>\n<p>**In huis**<br \/>\n- Meer rust, balans en gezelligheid<br \/>\n- Een vredige nachtrust<br \/>\n- Minder hoofdpijn of vermoeidheid<br \/>\n- Planten en dieren reageren positief<br \/>\n- Je voelt je echt weer welkom in je eigen huis<\/p>\n<p>**Op het werk**<br \/>\n- Betere focus en samenwerking<br \/>\n- Verhoogde productiviteit en creativiteit<br \/>\n- Meer werkplezier<\/p>\n<p>**Op school**<br \/>\n- Kinderen zijn rustiger en geconcentreerder<br \/>\n- Meer plezier in lesgeven<br \/>\n- Betere leerresultaten en meer plezier<\/p>\n<p>Een energetische huisreiniging in Boechout<br \/>\nzorgt voor een voelbare energetische reset.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Wat_kost_een_energetische_huisreiniging\"><\/span>Wat kost een energetische huisreiniging?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wat kost een energetische huisreiniging?<\/p>\n<p>De prijzen beginnen bij **\u20ac 323,-**<br \/>\nvoor een gemiddeld huis.<br \/>\nVoor andere woningtypes of panden<br \/>\nwordt een individuele berekening gemaakt.<\/p>\n<p>Afhankelijk van de locatie worden reiskosten gerekend,<br \/>\nzonder meer bij sessies buiten Boechout.<\/p>\n<p>Een huisreiniging in het buitenland<br \/>\nis in overleg te organiseren.<br \/>\nIk ben vaak actief in Zuid-Europa,<br \/>\nwat reiskosten kan verlagen.<\/p>\n<p>&nbsp;<\/p>\n<h2 data-start=\"471\" data-end=\"493\"><span class=\"ez-toc-section\" id=\"%F0%9F%8C%80Conclusie_en_combinatie_met_healing\"><\/span>\ud83c\udf00Conclusie en combinatie met healing:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Laat je omgeving weer ademen.<\/p>\n<p>Of het nu gaat om je huis, kantoor of klaslokaal -...<br \/>\neen energetische huisreiniging<br \/>\nkan direct voelbaar effect hebben op de<br \/>\nstemming van mens en dier.<\/p>\n<p>Luister naar je gevoel als je merkt dat er iets niet klopt<br \/>\nin je omgeving.<br \/>\nJe verdient een ruimte die je voedt en ondersteunt.<\/p>\n<p>In sommige gevallen is het waardevol om de ruimtehealing samen te doen met een individuele sessie.<br \/>\nDat werkt op persoonlijke energievelden,<br \/>\nwaardoor het resultaat krachtiger en blijvend is.<\/p>\n<p>Deze aanpak wordt regelmatig toegepast in Boechout<br \/>\nen biedt diepe transformatie.<\/p>\n<p>&nbsp;<\/p>\n<p>Neem contact op via Whatsapp +31 6 38398347 of met onderstaand formulier.<\/p>\n<div class=\"forminator-ui forminator-custom-form forminator-custom-form-150 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-150\" data-uid=\"6a57210a94ba2\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-150\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-150 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"150\"\n\t\t\t\t data-color-option=\"default\" data-design=\"default\" data-grid=\"open\" style=\"display: none;\"\n\t\t\t\tdata-uid=\"6a57210a94ba2\" action=\"\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-name-1_6a57210a94ba2\" id=\"forminator-field-name-1_6a57210a94ba2-label\" class=\"forminator-label\">Voornaam <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1\" value=\"\" placeholder=\"\" id=\"forminator-field-name-1_6a57210a94ba2\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"name-2\" class=\"forminator-field-name forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-name-2_6a57210a94ba2\" id=\"forminator-field-name-2_6a57210a94ba2-label\" class=\"forminator-label\">Achternaam <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-2\" value=\"\" placeholder=\"\" id=\"forminator-field-name-2_6a57210a94ba2\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"phone-1\" class=\"forminator-field-phone forminator-col forminator-col-12\"><div class=\"forminator-field\"><label for=\"forminator-field-phone-1_6a57210a94ba2\" id=\"forminator-field-phone-1_6a57210a94ba2-label\" class=\"forminator-label\">Telefoonnummer<\/label><input type=\"text\" name=\"phone-1\" value=\"\" placeholder=\"\" id=\"forminator-field-phone-1_6a57210a94ba2\" class=\"forminator-input forminator-field--phone\" data-required=\"\" aria-required=\"false\" autocomplete=\"off\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-4\"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a57210a94ba2\" id=\"forminator-field-email-1_6a57210a94ba2-label\" class=\"forminator-label\">E-mailadres <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"\" id=\"forminator-field-email-1_6a57210a94ba2\" class=\"forminator-input forminator-email--field\" data-required=\"true\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><div id=\"captcha-1\" class=\"forminator-field-captcha  forminator-col-4\"><div class=\"forminator-captcha-left forminator-g-recaptcha recaptcha-invisible\" data-theme=\"light\" data-badge=\"bottomright\" data-sitekey=\"6LeZ3CgqAAAAAOurPts9xhQkmYl-TBrc_QHZGS-Z\" data-size=\"invisible\"><\/div> <\/div><div id=\"textarea-1\" class=\"forminator-field-textarea forminator-col forminator-col-4\"><div class=\"forminator-field\"><label for=\"forminator-field-textarea-1_6a57210a94ba2\" id=\"forminator-field-textarea-1_6a57210a94ba2-label\" class=\"forminator-label\">Bericht<\/label><textarea name=\"textarea-1\" placeholder=\"Voer je bericht in...\" id=\"forminator-field-textarea-1_6a57210a94ba2\" class=\"forminator-textarea\" style=\"--forminator-textarea-min-height:140px;\" maxlength=\"180\" ><\/textarea><span id=\"forminator-field-textarea-1_6a57210a94ba2-description\" class=\"forminator-description\"><span data-limit=\"180\" data-type=\"characters\" data-editor=\"\">0 \/ 180<\/span><\/span><\/div><\/div><\/div><div class=\"forminator-row forminator-hidden\"><div id=\"hidden-1\" class=\"forminator-field-hidden  forminator-col-12\"><input type=\"hidden\" id=\"hidden-1_6a57210a94ba2\" name=\"hidden-1\" value=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/\" \/><\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">Bericht verzenden<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"e3a36e4f47\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/nl\/wp-json\/wp\/v2\/posts\/25725\" \/><input type=\"hidden\" name=\"form_id\" value=\"150\"><input type=\"hidden\" name=\"page_id\" value=\"25725\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><label for=\"input_7\" class=\"forminator-hidden\" aria-hidden=\"true\">Voer dit veld niet in. <input id=\"input_7\" type=\"text\" name=\"input_7\" value=\"\" autocomplete=\"off\"><\/label><input type=\"hidden\" name=\"trp-form-language\" value=\"nl\"\/><\/form>","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf00Titel: Helende Huisreiniging in Boechout: Breng Harmonie Terug \ud83c\udf00Inleiding: Een energetische huisreiniging is een effectieve manier om energetische blokkades uit je woning te verwijderen. Wanneer je merkt dat er onverklaarbare vermoeidheid of irritatie ontstaat, kan een huisreiniging een verlichting bieden. De energetische zuivering kan plaatsvinden in de Boechout. In overleg is een energetische reiniging wereldwijd &hellip; <a href=\"https:\/\/abstruse.nl\/nl\/energetische-opschoning-van-ruimtes-in-boechout-pageid-142\/\" class=\"more-link\">Verder lezen<span class=\"screen-reader-text\"> &#8220;Energetische Opschoning van Ruimtes in Boechout PageID= 142&#8221;<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_page_generator_pro_exclude":false,"_page_generator_pro_group":1766,"_page_generator_pro_index":942,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25725","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/posts\/25725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/comments?post=25725"}],"version-history":[{"count":0,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/posts\/25725\/revisions"}],"wp:attachment":[{"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/media?parent=25725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/categories?post=25725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abstruse.nl\/nl\/wp-json\/wp\/v2\/tags?post=25725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}